{"id":123007,"date":"2022-10-25T13:30:58","date_gmt":"2022-10-25T11:30:58","guid":{"rendered":"https:\/\/www.esmuc.cat\/assignatures\/cap-a-una-nova-pedagogia-musical\/"},"modified":"2022-10-25T13:30:58","modified_gmt":"2022-10-25T11:30:58","slug":"cap-a-una-nova-pedagogia-musical","status":"publish","type":"assignatures","link":"https:\/\/www.esmuc.cat\/es\/assignatures\/cap-a-una-nova-pedagogia-musical\/","title":{"rendered":"Cap a una nova pedagogia musical"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-123007","assignatures","type-assignatures","status-publish","hentry"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.esmuc.cat\/es\/wp-json\/wp\/v2\/assignatures\/123007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esmuc.cat\/es\/wp-json\/wp\/v2\/assignatures"}],"about":[{"href":"https:\/\/www.esmuc.cat\/es\/wp-json\/wp\/v2\/types\/assignatures"}],"wp:attachment":[{"href":"https:\/\/www.esmuc.cat\/es\/wp-json\/wp\/v2\/media?parent=123007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}