{"id":89941,"date":"2024-01-22T13:07:34","date_gmt":"2024-01-22T12:07:34","guid":{"rendered":"https:\/\/www.esmuc.cat\/professorat\/alba-roca\/"},"modified":"2024-01-23T10:21:51","modified_gmt":"2024-01-23T09:21:51","slug":"alba-roca","status":"publish","type":"professorat","link":"https:\/\/www.esmuc.cat\/en\/professorat\/alba-roca\/","title":{"rendered":"Alba Roca"},"content":{"rendered":"","protected":false},"featured_media":23178,"template":"","class_list":["post-89941","professorat","type-professorat","status-publish","has-post-thumbnail","hentry"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.esmuc.cat\/en\/wp-json\/wp\/v2\/professorat\/89941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esmuc.cat\/en\/wp-json\/wp\/v2\/professorat"}],"about":[{"href":"https:\/\/www.esmuc.cat\/en\/wp-json\/wp\/v2\/types\/professorat"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esmuc.cat\/en\/wp-json\/wp\/v2\/media\/23178"}],"wp:attachment":[{"href":"https:\/\/www.esmuc.cat\/en\/wp-json\/wp\/v2\/media?parent=89941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}